{"id":1352,"date":"2023-11-20T19:52:54","date_gmt":"2023-11-20T19:52:54","guid":{"rendered":"http:\/\/acodalej.sk\/?page_id=1352"},"modified":"2025-03-19T07:52:45","modified_gmt":"2025-03-19T07:52:45","slug":"casova-os","status":"publish","type":"page","link":"https:\/\/acodalej.sk\/es\/casova-os\/","title":{"rendered":"Cronolog\u00eda"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1352\" class=\"elementor elementor-1352\">\n\t\t\t\t<div class=\"has_eae_slider elementor-element elementor-element-971c1ce e-con-full e-flex e-con e-parent\" data-eae-slider=\"26811\" data-id=\"971c1ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d335586 image-position-column elementor-widget elementor-widget-eae-timeline\" data-id=\"d335586\" data-element_type=\"widget\" data-widget_type=\"eae-timeline.skin1\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section data-layout=\"center\" data-top-offset=\"100\" class=\"eae-layout-center eae-timeline eae-timeline-alternate-no eae-tl-center eae-tl-res-style-mobile eae-tl-res-layout-left\">\n\t\t\t<div class=\"eae-timline-progress-bar\">\n\t\t\t\t<div class='eae-pb-inner-line'><\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"06f746a\" class=\"eae-timeline-item elementor-repeater-item-06f746a custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"06f746a\">\n\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/stvorenie-sveta\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"538\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/raj-768x538.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1408\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/raj-768x538.jpg 768w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/raj-300x210.jpg 300w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/raj-1024x717.jpg 1024w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/raj-1536x1076.jpg 1536w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/raj.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">Creaci\u00f3n del mundo<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 0<br \/>nuestra era 3760 a.C.<\/p><p>Descripci\u00f3n b\u00edblica de la creaci\u00f3n del cielo y la tierra. El Creador plane\u00f3, habl\u00f3 y sucedi\u00f3. El hombre fue creado a imagen de Dios con la tarea de gobernar la tierra. El origen de la semana de siete d\u00edas, que se ha utilizado a lo largo de la historia de la humanidad hasta nuestros d\u00edas. Un ser oscuro en forma de serpiente arrebat\u00f3 el poder a los primeros pueblos, convirti\u00e9ndolos en esclavos de este ser. Dios prometi\u00f3 que vendr\u00eda un descendiente humano: un Salvador que aplastar\u00eda la cabeza de la serpiente. Una descripci\u00f3n precisa del lugar de residencia de los primeros pueblos entre los r\u00edos \u00c9ufrates, Tigris, Pis\u00f3n y Gih\u00f3n. Una lista precisa de los nombres de los descendientes de los primeros pueblos y sus a\u00f1os de vida en la tierra.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"eb70a4e\" class=\"eae-timeline-item elementor-repeater-item-eb70a4e custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"eb70a4e\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/potopa\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img decoding=\"async\" width=\"347\" height=\"210\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/potopa.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1472\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/potopa.jpg 347w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/potopa-300x182.jpg 300w\" sizes=\"(max-width: 347px) 100vw, 347px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">Inundaci\u00f3n<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 1556<\/p><p style=\"text-align: left\">nuestro a\u00f1o 2204 a.C.<\/p><p>La rebeli\u00f3n de la gente contra el Creador se generaliz\u00f3. Pocas personas honraban a Dios y su Palabra, a quienes Dios les hablaba. Dios envi\u00f3 a estas personas para advertirles contra las malas acciones. Se burlaron de Dios y de sus mensajeros. Dios decidi\u00f3 causar un diluvio universal en la Tierra y eliminar a la humanidad pervertida. El diluvio signific\u00f3 que el agua alcanz\u00f3 su punto m\u00e1ximo a 7,5 m sobre las monta\u00f1as m\u00e1s altas del mundo. La columna de agua en la Tierra alcanz\u00f3 su punto m\u00e1ximo de unos 9 km. La duraci\u00f3n del diluvio fue de 150 d\u00edas. Ni siquiera podemos imaginar la afluencia de madera, piedras, arcilla, cuerpos de animales y personas en los valles. Cuando tenemos un breve descanso de media hora, tenemos que palear el barro de los caminos y limpiar los lechos de los r\u00edos de troncos, \u00e1rboles y otros materiales arrastrados por la corriente. Dios dej\u00f3 a No\u00e9 con su familia, ocho personas en total, porque No\u00e9 respetaba al Creador, el Dador de la vida. Dios le advirti\u00f3 de antemano lo que suceder\u00eda y c\u00f3mo prepararse. Se le dio un plano preciso del barco en el que deb\u00eda sobrevivir al diluvio. Tras el diluvio, desembarcaron en el monte Ararat, en lo que hoy es Turqu\u00eda. Los genetistas han descubierto el origen de algunas plantas cultivadas en las cercan\u00edas de este monte. El s\u00edmbolo actual de la paz \u2014una paloma con una rama de olivo en el pico\u2014 recuerda el juicio de Dios sobre la tierra. Otro s\u00edmbolo es el arco\u00edris, s\u00edmbolo de la infancia y un nuevo comienzo. Es bueno recordar y narrar el diluvio hist\u00f3rico cuando se ve un arco\u00edris en la naturaleza.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"4cd79d5\" class=\"eae-timeline-item elementor-repeater-item-4cd79d5 custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"4cd79d5\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/zrod-narodov\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img decoding=\"async\" width=\"768\" height=\"871\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylonskaveza-768x871.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1434\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylonskaveza-768x871.jpg 768w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylonskaveza-264x300.jpg 264w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylonskaveza.jpg 787w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">  Nacimiento de las Naciones - Patriarcas<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 1556<br \/>nuestra era 2204 a. C.<\/p><p style=\"text-align: left\">\u00a0<\/p><p>La Biblia contiene una lista de los patriarcas de las naciones futuras. No\u00e9 tuvo tres hijos: Sem, Cam y Jafet. Los t\u00e9rminos \u00absemita\u00bb y \u00abantisemitismo\u00bb derivan del nombre Sem. Estas son las naciones del Cercano Oriente. El antiguo imperio babil\u00f3nico de Nimrod y la Torre de Babel, una nueva rebeli\u00f3n del pueblo contra Dios. Un esfuerzo por demostrar que con nuestras capacidades humanas, sin el Creador, alcanzaremos la inmortalidad y crearemos leyes seg\u00fan nuestras ideas, deseos y sentimientos. Esto implica ignorar al Gobernante del cielo y la tierra y las leyes que \u00c9l estableci\u00f3 en la creaci\u00f3n, hasta el punto de derrocarlo del trono. La manifestaci\u00f3n de esta oposici\u00f3n-rebeli\u00f3n es derrocar a todas las autoridades, como los padres de familia, las autoridades naturales de la sociedad y los gobernantes seculares, con el resultado de caos, anarqu\u00eda; en t\u00e9rminos b\u00edblicos, Babilonia. El lema de la rebeli\u00f3n del pueblo contra Dios: \u00abComamos, bebamos y celebremos, porque ma\u00f1ana moriremos; hagamos lo que queramos y sintamos\u00bb. A pesar de los esfuerzos humanos, Dios fue, es y ser\u00e1.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"89bfb73\" class=\"eae-timeline-item elementor-repeater-item-89bfb73 custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"89bfb73\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/vznik-izraela\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/abraham-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1428\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/abraham-768x432.jpg 768w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/abraham-300x169.jpg 300w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/abraham-1024x576.jpg 1024w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/abraham.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">El nacimiento de la naci\u00f3n de Israel<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 1760<br \/>nuestra era 2000 a. C.<\/p><p>\u00a0<\/p><p>Dios apart\u00f3 a una peque\u00f1a naci\u00f3n del mundo para cumplir su prop\u00f3sito supremo para la humanidad: darnos la oportunidad de regresar a \u00c9l, nuestro Padre. La historia de esta naci\u00f3n comienza con la familia donde creci\u00f3 Abraham. Esta familia viv\u00eda en el coraz\u00f3n del antiguo imperio babil\u00f3nico, en la ciudad de Ur, donde excavaciones han encontrado inodoros con cisterna y agua caliente y fr\u00eda en el sistema de agua de la ciudad. Dios le dijo a Abraham que dar\u00eda a sus descendientes la tierra de Cana\u00e1n despu\u00e9s de 430 a\u00f1os de cautiverio en Egipto. Todas estas profec\u00edas se cumplieron. Dios levant\u00f3 a Mois\u00e9s para guiar a la naci\u00f3n de Israel, compuesta por 600.000 hombres, fuera de Egipto. Este era un grupo de aproximadamente dos millones de personas que vieron c\u00f3mo Dios azotaba a Egipto con plagas, la \u00faltima de las cuales fue la muerte de todos los primog\u00e9nitos egipcios, porque los egipcios asesinaban a los hijos de los israelitas. Despu\u00e9s de diez terribles plagas, los egipcios liberaron a la naci\u00f3n de Israel. Mientras hu\u00edan, fueron emboscados por el ej\u00e9rcito egipcio en el Mar Rojo, donde Dios abri\u00f3 el mar, los israelitas cruzaron y el ej\u00e9rcito egipcio se ahog\u00f3. Luego caminaron por el desierto en la tierra de Madi\u00e1n-Arabia, donde Dios les provey\u00f3 de su palabra, alimento y bebida en su lugar de residencia. En el desierto, recibieron la ley de justicia de Dios: los Diez Mandamientos, que ninguno de nosotros puede cumplir. Por lo tanto, parte de la ley es la promesa del Salvador del mundo, para que ninguno de nosotros pueda jactarse de no necesitar la ayuda de Dios. Debido a su rebeli\u00f3n contra Dios, vagaron por el desierto durante 40 a\u00f1os y finalmente entraron en la tierra que Dios le prometi\u00f3 a Abraham. El texto b\u00edblico contiene los lugares exactos de los eventos descritos, los per\u00edodos de tiempo y los nombres de personas espec\u00edficas y linajes completos.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"3f538d8\" class=\"eae-timeline-item elementor-repeater-item-3f538d8 custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"3f538d8\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/izrael-v-zaslubenej-zemi\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"354\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/kanan.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1453\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/kanan.jpg 500w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/kanan-300x212.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">Israel en la Tierra Prometida<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 2260 - 3174<br \/>Nuestro calendario 1500 - 586 a. C.<\/p><p>\u00a0<\/p><p>La naci\u00f3n de Israel fue conducida por Dios a la tierra de Cana\u00e1n, la cual Dios prometi\u00f3 a Abraham y a sus descendientes. Israel recibi\u00f3 la ley divina: los Diez Mandamientos. Cuando intentaron seguir esta ley, Dios estuvo con ellos y prosperaron. Al seguir las normas de vida de las naciones vecinas, se alejaron de Dios y cayeron bajo la opresi\u00f3n de fuerzas oscuras a trav\u00e9s de sequ\u00edas, enfermedades y la opresi\u00f3n de las naciones vecinas. En ese momento, enfermaron y clamaron a Dios por perd\u00f3n y liberaci\u00f3n. Dios entonces les envi\u00f3 liberadores-jueces, a trav\u00e9s de quienes aprendieron a vivir seg\u00fan las normas de vida divinas. Entonces, Dios san\u00f3 sus vidas, familias y pa\u00eds, y los libr\u00f3 de la opresi\u00f3n de las naciones vecinas. Despu\u00e9s de m\u00e1s de 400 a\u00f1os, los israelitas pidieron un rey como las naciones vecinas. El per\u00edodo de los reyes dur\u00f3 m\u00e1s de 400 a\u00f1os, durante los cuales los israelitas se alejaron gradualmente de Dios. Dios los llam\u00f3 a regresar a trav\u00e9s de los profetas. La naci\u00f3n de Israel permiti\u00f3 que Satan\u00e1s los guiara por malos caminos. Dios puso fin a este per\u00edodo con la destrucci\u00f3n de Jerusal\u00e9n y el cautiverio babil\u00f3nico del remanente de la naci\u00f3n durante 70 a\u00f1os. En la Biblia, Dios describe eventos, lugares y nombres espec\u00edficos.\u00a0<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"15d8535\" class=\"eae-timeline-item elementor-repeater-item-15d8535 custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"15d8535\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/svetove-staroveke-rise\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylon-768x432.webp\" class=\"attachment-medium_large size-medium_large wp-image-1432\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylon-768x432.webp 768w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylon-300x169.webp 300w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylon-1024x576.webp 1024w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylon-1536x864.webp 1536w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/babylon-2048x1152.webp 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">Los antiguos imperios del mundo<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 3174 - 4236<br \/>Nuestro calendario 586 a. C. - 476 d. C.<\/p><p>\u00a0<\/p><p>Tras la destrucci\u00f3n del Reino de Jud\u00e1 (586 a. C.), el rey del Imperio Neobabil\u00f3nico, Nabucodonosor II (605-562 a. C.), se preguntaba qu\u00e9 suceder\u00eda con su imperio y el mundo. Dios le concedi\u00f3 un sue\u00f1o que lo perturb\u00f3 profundamente, y pidi\u00f3 a sus consejeros que le explicaran el sue\u00f1o y su interpretaci\u00f3n. Un joven llamado Daniel, uno de los cautivos de Jud\u00e1, fue encontrado y le pidi\u00f3 al Dios Todopoderoso de Israel que viera el sue\u00f1o y lo interpretara. Dios lo escuch\u00f3. En el sue\u00f1o, Dios revel\u00f3 al rey, al pueblo de aquel tiempo y a nosotros hoy, acontecimientos futuros. El relato b\u00edblico describe los acontecimientos del Imperio Neobabil\u00f3nico tras su fin y el auge del Imperio Persa con el regreso de los jud\u00edos a su tierra y la restauraci\u00f3n de Jerusal\u00e9n y el templo del Dios del cielo. El Salvador del mundo, Jes\u00fas de Nazaret, lleg\u00f3 a este templo de Jerusal\u00e9n 500 a\u00f1os despu\u00e9s, tal como se predijo.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"979e7e9\" class=\"eae-timeline-item elementor-repeater-item-979e7e9 custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"979e7e9\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/jezis-nazaretsky-zachranca-sveta\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"538\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/jezis-768x538.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1450\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/jezis-768x538.jpg 768w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/jezis-300x210.jpg 300w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/jezis.jpg 992w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">Jes\u00fas de Nazaret \u2013 Salvador del mundo<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 3754 - 3794<br \/>Nuestro calendario 6 a. C. - 34 d. C.<\/p><p>\u00a0<\/p><p>La descripci\u00f3n de la venida, la vida, las palabras y la obra del Salvador para todo el mundo se predice en la Biblia con miles de a\u00f1os de anticipaci\u00f3n y se describe en cuatro libros b\u00edblicos bajo el t\u00edtulo griego Evangelio - Mensaje de Victoria. La vida de Jesucristo es un ejemplo de Dios para cada uno de nosotros.<\/p><p>Jes\u00fas dijo: <em>&quot;Yo soy el \u00fanico camino, la verdad y la vida; nadie viene al Padre sino por m\u00ed.&quot;\u00a0<\/em><\/p><p>\u00c9l pag\u00f3 con su vida el rescate por cada uno de nosotros, para que no seamos esclavos del mal, sino hijos libres de Dios.\u00a0<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"2761a96\" class=\"eae-timeline-item elementor-repeater-item-2761a96 custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta\">\n\t\t\t\t\t\t\t4100 \/ 100 d. C.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"2761a96\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/cirkev-zhromazdenie-ludi-k-uctievaniu-boha\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"360\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/prvacirkev-768x360.png\" class=\"attachment-medium_large size-medium_large wp-image-1463\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/prvacirkev-768x360.png 768w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/prvacirkev-300x141.png 300w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/prvacirkev-1024x480.png 1024w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/prvacirkev-1536x721.png 1536w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/prvacirkev.png 1586w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t4100 \/ 100 d. C.\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">Iglesia: una reuni\u00f3n de personas para adorar a Dios.<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 3794<br \/>34 d. C.<\/p><p>\u00a0<\/p><p>Los acontecimientos posteriores a la resurrecci\u00f3n del Se\u00f1or Jes\u00fas se registran en el libro de los Hechos de los Ap\u00f3stoles. Este libro describe la uni\u00f3n de pueblos de todas las naciones del mundo con Israel, la cual Dios anunci\u00f3 a los profetas con siglos de antelaci\u00f3n. Los libros que describen los acontecimientos que cumplieron las predicciones de los profetas se complementan con libros que explican la ley y la historia de Dios para quienes creen que Jes\u00fas de Nazaret es Dios, verdadero hombre y el Salvador del mundo. Los libros se complementan con otras profec\u00edas para el futuro, que describen el fin del mundo presente y el venidero.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div id=\"0f7b1a7\" class=\"eae-timeline-item elementor-repeater-item-0f7b1a7 custom-image-style-no image-position-\">\n\n\t\t\t\t<div class=\"eae-tl-item-meta-wrapper\">\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"eae-tl-icon-wrapper\" id=\"0f7b1a7\">\n\t\t\t\t\t\t\t\t<div class=\"eae-icon eae-icon-item_icon eae-icon-view-framed eae-icon-shape-circle eae-icon-type-text\">\n\t\t\t\t<div class=\"eae-icon-wrap\">\n\t\t\t\t\t<i class=\"\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-tl-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/acodalej.sk\/es\/a-co-dalej\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-content\">\n\t\t\t\t\t\t\t<div class='eae-tl-item-image'><img loading=\"lazy\" decoding=\"async\" width=\"626\" height=\"360\" src=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/sucastnost.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1468\" alt=\"\" srcset=\"https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/sucastnost.jpg 626w, https:\/\/acodalej.sk\/wp-content\/uploads\/2023\/11\/sucastnost-300x173.jpg 300w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"eae-tl-content\">\n\t\t\t\t\t\t\t\t<div class=\"eae-content-inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-tl-item-meta-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<h3 class=\"eae-tl-item-title\">\u00bfQu\u00e9 sigue?<\/h3><div class=\"eae-tl-content-innner\"><p style=\"text-align: left\">A\u00f1o jud\u00edo 5784<br \/>nuestro a\u00f1o 2024 d.C.<\/p><p>\u00a0<\/p><p>La Biblia describe el pasado, el presente y el futuro. En cuanto al futuro, aborda el destino de las personas, el pueblo de Dios, Israel, la sucesi\u00f3n de imperios mundiales, la predicaci\u00f3n del mensaje de salvaci\u00f3n de Dios a la gente de todo el mundo en la persona de Jes\u00fas de Nazaret, terremotos, hambrunas, epidemias, guerras (Armaged\u00f3n), la destrucci\u00f3n del sistema babil\u00f3nico, la venida del anticristo con la se\u00f1al del 666, el reino de mil a\u00f1os de Jesucristo, el juicio final y el veredicto final sobre cada ser: cielo o infierno.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/section>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Stvorenie sveta \u017eidovsky rok 0n\u00e1\u0161 letopo\u010det 3760 pnl. Biblick\u00fd popis stvorenia neba a zeme. Stvorite\u013e napl\u00e1noval, povedal a stalo sa. \u010clovek stvoren\u00fd na obraz Boha s \u00falohou vl\u00e1dy nad zemou. P\u00f4vod siedmich dn\u00ed t\u00fd\u017ed\u0148a, ktor\u00fd sa pou\u017e\u00edva cel\u00e9 dejiny \u013eudstva dodnes. Prv\u00ed \u013eudia si nechali vl\u00e1du od Boha ukradn\u00fa\u0165 temnou bytos\u0165ou v podobe hada a [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"disabled","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1352","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/acodalej.sk\/es\/wp-json\/wp\/v2\/pages\/1352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acodalej.sk\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/acodalej.sk\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/acodalej.sk\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acodalej.sk\/es\/wp-json\/wp\/v2\/comments?post=1352"}],"version-history":[{"count":0,"href":"https:\/\/acodalej.sk\/es\/wp-json\/wp\/v2\/pages\/1352\/revisions"}],"wp:attachment":[{"href":"https:\/\/acodalej.sk\/es\/wp-json\/wp\/v2\/media?parent=1352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}